{"id":1121,"date":"2023-09-11T16:32:36","date_gmt":"2023-09-11T14:32:36","guid":{"rendered":"https:\/\/atos-mvz.de\/wiesbaden\/?page_id=1121"},"modified":"2023-09-11T17:09:11","modified_gmt":"2023-09-11T15:09:11","slug":"hueftgelenkarthrose","status":"publish","type":"page","link":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/","title":{"rendered":"H\u00fcftgelenkarthrose"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-641mc1-67035a8b43cb39bea936f1148794af3b\">\n.avia-section.av-641mc1-67035a8b43cb39bea936f1148794af3b{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2021\/01\/Hueftschmerzen_1700x600.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n.avia-section.av-641mc1-67035a8b43cb39bea936f1148794af3b .av-extra-border-element .av-extra-border-inner{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='header-img'  class='avia-section av-641mc1-67035a8b43cb39bea936f1148794af3b main_color avia-section-huge avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch avia-bg-style-scroll container_wrap fullsize'  data-section-bg-repeat='stretch'><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-1121'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4sx5sx-6af28c5c4f42910fe6bb752420299f46\">\n#top .hr.hr-invisible.av-4sx5sx-6af28c5c4f42910fe6bb752420299f46{\nheight:100px;\n}\n<\/style>\n<div  class='hr av-4sx5sx-6af28c5c4f42910fe6bb752420299f46 hr-invisible  avia-builder-el-1  avia-builder-el-no-sibling '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><div class='av-extra-border-element border-extra-diagonal border-extra-diagonal-inverse '><div class='av-extra-border-outer'><div class='av-extra-border-inner'><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lmezdlts-e3ae5b1e8ad83195ccf16fe58b55a9a9\">\n.avia-section.av-lmezdlts-e3ae5b1e8ad83195ccf16fe58b55a9a9 .av-extra-border-element .av-extra-border-inner{\nbackground-color:#f1f0f5;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-lmezdlts-e3ae5b1e8ad83195ccf16fe58b55a9a9 main_color avia-section-large avia-no-border-styling  avia-builder-el-2  el_after_av_section  avia-builder-el-last  small-container avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-1121'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-lmezei17-59f6b659604149c39c10696e660f2406 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1><strong>H\u00fcftgelenkarthrose<\/strong><\/h1>\n<p>Allgemeine Informationen<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3977ap-6068b5abbd7b6f8798e01a00890be468\">\n#top .hr.av-3977ap-6068b5abbd7b6f8798e01a00890be468{\nmargin-top:0;\nmargin-bottom:30px;\n}\n.hr.av-3977ap-6068b5abbd7b6f8798e01a00890be468 .hr-inner{\nwidth:100%;\nborder-color:#f1f0f5;\n}\n<\/style>\n<div  class='hr av-3977ap-6068b5abbd7b6f8798e01a00890be468 hr-custom  avia-builder-el-4  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-lmezf4ds-a136f3f2792f527af9b6dad4d48c1d05 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 class=\"h-custom-headline man h4\"><strong>Was ist eine Arthrose?<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1123 size-medium alignright\" src=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte-300x158.jpg 300w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte-1030x542.jpg 1030w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte-768x404.jpg 768w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte-710x375.jpg 710w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte-705x371.jpg 705w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte.jpg 1172w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>Arthrose ist gleichzusetzen mit dem Verlust von Gelenkknorpel<\/strong><\/p>\n<p>Unter Arthrose versteht man einen \u201eGelenkverschlei\u00df\u201c, der das alters\u00fcbliche Ma\u00df \u00fcbersteigt. Das hei\u00dft, der Knorpel geht langsam zu Grunde.<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2goyup-244978c1a8d80d0cbb020c088f6c2ad8\">\n#top .hr.av-2goyup-244978c1a8d80d0cbb020c088f6c2ad8{\nmargin-top:20px;\nmargin-bottom:30px;\n}\n.hr.av-2goyup-244978c1a8d80d0cbb020c088f6c2ad8 .hr-inner{\nwidth:100%;\nborder-color:#f1f0f5;\n}\n<\/style>\n<div  class='hr av-2goyup-244978c1a8d80d0cbb020c088f6c2ad8 hr-custom  avia-builder-el-6  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-lmezlzmt-d21562d983a5575f7dc89529b369cb1b '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><strong>Welche Formen gibt es und was ist die Ursache?<br \/>\n<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1134 size-medium alignright\" src=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/arthrotische_huefte-300x154.jpg\" alt=\"\" width=\"300\" height=\"154\" srcset=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/arthrotische_huefte-300x154.jpg 300w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/arthrotische_huefte.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>Eine Arthrose kann viele Ursachen haben<\/strong><\/p>\n<p>Wir unterscheiden eine \u201eprim\u00e4re\u201c Arthrose, bei der man von einer biologischen Minderwertigkeit des Knorpelgewebes ausgeht von einer so genannten \u201esekund\u00e4ren\u201c Arthrose. Hierbei steht im Vordergrund eine \u00fcberm\u00e4\u00dfige Belastung des Gelenkes wobei das \u00dcbergewicht hier eine dominierende Rolle spielt.<\/p>\n<p>Ursachen f\u00fcr sekund\u00e4re Arthrosen k\u00f6nnen angeborene oder traumatisch bedingte Fehlstellungen der Gelenke sein. H\u00e4ufig findet sich ein erh\u00f6hter oder reduzierter Schenkelhalswinkel, der zu einer vermehrten Belastung des Gelenkknorpels f\u00fchrt. Gelegentlich leiden auch Patienten mit einer so genannten H\u00fcftdysplasie, also einer den H\u00fcftkopf nicht ausreichend umschlie\u00dfenden H\u00fcftpfanne, unter dem fr\u00fchen Auftreten einer Arthrose.<\/p>\n<p>Die Arthrose kann ebenfalls als Folge von entz\u00fcndlichen, meist rheumatischen Erkrankungen auftreten. Grunds\u00e4tzlich k\u00f6nnen alle Gelenke eine Arthrose entwickeln. In Deutschland ist das Kniegelenk am h\u00e4ufigsten betroffen.<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5z45g1-1e766fc0a38e9112f1808199a8facb24\">\n#top .hr.av-5z45g1-1e766fc0a38e9112f1808199a8facb24{\nmargin-top:20px;\nmargin-bottom:30px;\n}\n.hr.av-5z45g1-1e766fc0a38e9112f1808199a8facb24 .hr-inner{\nwidth:100%;\nborder-color:#f1f0f5;\n}\n<\/style>\n<div  class='hr av-5z45g1-1e766fc0a38e9112f1808199a8facb24 hr-custom  avia-builder-el-8  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-lmezrvne-e5909caed1c44a4ea297360fe77a5a52 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><strong>Welche Stadien werden unterschieden?<\/strong><\/h2>\n<p>Wir unterscheiden vier Stadien der Arthroseentwicklung:<\/p>\n<ul>\n<li>Im <strong>Stadium 1<\/strong> finden wir eine Ausd\u00fcnnung und Aufweichung der Knorpelschicht.<\/li>\n<li>Im <strong>Stadium 2<\/strong> treten dann bereits kleine Risse und Aufrauungen der Knorpeloberfl\u00e4che auf.<\/li>\n<li>Im <strong>Stadium 3<\/strong> kommt es dann zu tieferen Defekten, der Knorpel wird teilweise durch minderwertigeres Gewebe ersetzt.<\/li>\n<li>Im <strong>Stadium 4<\/strong> liegt der Knochen gro\u00dffl\u00e4chig frei. Um den Druck auf das Gelenk zu reduzieren, bilden sich so genannte Osteophyten (Randw\u00fclste am Knochen) aus.<\/li>\n<\/ul>\n<p><div id=\"attachment_1141\" style=\"width: 264px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1141\" class=\"size-medium wp-image-1141\" src=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte_roentgenbild-254x300.png\" alt=\"\" width=\"254\" height=\"300\" srcset=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte_roentgenbild-254x300.png 254w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte_roentgenbild.png 312w\" sizes=\"auto, (max-width: 254px) 100vw, 254px\" \/><p id=\"caption-attachment-1141\" class=\"wp-caption-text\">Gesunde H\u00fcfte<\/p><\/div><br \/>\n<div id=\"attachment_1142\" style=\"width: 264px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1142\" class=\"size-medium wp-image-1142\" src=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/erkrankte_huefte_roentgen-1-254x300.jpg\" alt=\"\" width=\"254\" height=\"300\" srcset=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/erkrankte_huefte_roentgen-1-254x300.jpg 254w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/erkrankte_huefte_roentgen-1.jpg 312w\" sizes=\"auto, (max-width: 254px) 100vw, 254px\" \/><p id=\"caption-attachment-1142\" class=\"wp-caption-text\">Erkrankte H\u00fcfte<\/p><\/div><\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3lqdkx-48a96ae5abb0da48c4a22d3cff051bd7\">\n#top .hr.av-3lqdkx-48a96ae5abb0da48c4a22d3cff051bd7{\nmargin-top:20px;\nmargin-bottom:30px;\n}\n.hr.av-3lqdkx-48a96ae5abb0da48c4a22d3cff051bd7 .hr-inner{\nwidth:100%;\nborder-color:#f1f0f5;\n}\n<\/style>\n<div  class='hr av-3lqdkx-48a96ae5abb0da48c4a22d3cff051bd7 hr-custom  avia-builder-el-10  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-lmezt4x6-b4bbd106645a13c1118dd5c824d2f082 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><strong>Welche Probleme treten auf?<\/strong><\/h2>\n<p>Eine Arthrose kann durchaus asymptomatisch sein. In der Regel beklagen die Patienten jedoch anlauf- und belastungsabh\u00e4ngige Schmerzen. Diese korrelieren nicht immer mit der Auspr\u00e4gung des Arthrosegrades. Weiter typische Symptome sind ein Gelenkerguss. Dieser zeigt sich vor allem bei einer aktivierten Arthrose. Im zunehmenden Verlauf kommt es dann zu einer Verformung des Gelenks mit Ger\u00e4uschen durch zunehmende Unebenheiten der Knorpeloberfl\u00e4che.<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1xot81-10d0aa5bb6923730a6bdd7e157c85e71\">\n#top .hr.av-1xot81-10d0aa5bb6923730a6bdd7e157c85e71{\nmargin-top:20px;\nmargin-bottom:30px;\n}\n.hr.av-1xot81-10d0aa5bb6923730a6bdd7e157c85e71 .hr-inner{\nwidth:100%;\nborder-color:#f1f0f5;\n}\n<\/style>\n<div  class='hr av-1xot81-10d0aa5bb6923730a6bdd7e157c85e71 hr-custom  avia-builder-el-12  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-lmeztmu1-3ca2bd13d774a51030991b44ec1cbfd2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><strong>Welche Untersuchungen sind notwendig?<\/strong><\/h2>\n<p><strong>Mittels einer R\u00f6ntgenaufnahme ist die Arthrose gut zu diagnostizieren.<\/strong><\/p>\n<p>Nach der Erhebung der Krankengeschichte schlie\u00dft sich die klinische Untersuchung des Gelenkes an. Wir untersuchen die Funktion, die Beweglichkeit, beurteilen die Beinachse und k\u00f6nnen gegebenenfalls mittels einer Ultraschalluntersuchung einen Erguss im H\u00fcftgelenk erkennen.<\/p>\n<p>Bez\u00fcglich der weiteren bildgebenden Diagnostik steht hier das R\u00f6ntgenbild an erster Stelle.<br \/>\nWir achten dabei auf eine Verschm\u00e4lerung des Gelenkspaltes, eine Sklerose (reaktive Knochenverdichtung unterhalb des Gelenkspaltes), Osteophyten und Zystenbildungen.<\/p>\n<p>Fast immer kann dadurch die Diagnose bzw. das Ausma\u00df der Arthrose ausreichend beurteilt werden.<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2qfu0x-d925bdbc82fd9f0515afe1cd68e528d8\">\n#top .hr.av-2qfu0x-d925bdbc82fd9f0515afe1cd68e528d8{\nmargin-top:20px;\nmargin-bottom:30px;\n}\n.hr.av-2qfu0x-d925bdbc82fd9f0515afe1cd68e528d8 .hr-inner{\nwidth:100%;\nborder-color:#f1f0f5;\n}\n<\/style>\n<div  class='hr av-2qfu0x-d925bdbc82fd9f0515afe1cd68e528d8 hr-custom  avia-builder-el-14  el_after_av_textblock  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-lmezuf37-c0ba26dd82bbc6c5242bde3a43226001 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><strong>Welche Therapiem\u00f6glichkeiten gibt es?<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1117 alignright\" src=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/Erkrankungen-am-Hueftgelenk-300x286.jpg\" alt=\"\" width=\"300\" height=\"286\" srcset=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/Erkrankungen-am-Hueftgelenk-300x286.jpg 300w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/Erkrankungen-am-Hueftgelenk.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>Die konservativen Therapieoptionen der Arthrose sind begrenzt.<\/strong><\/p>\n<p>Leider ist die Arthrose, egal welche Ursache sie hat, immer noch nicht heilbar.<\/p>\n<p>Einmal streben wir nat\u00fcrlich nach Schmerzfreiheit oder zumindest einer deutlichen Schmerzreduktion, zum Zweiten m\u00f6chten wir mechanische Einschr\u00e4nkungen oder Ver\u00e4nderungen des Gelenkes verhindern.<\/p>\n<p>Im Anfangsstadium empfehlen wir ausreichende Bewegung ohne \u00dcberlastung und ganz besonders die Vermeidung bzw. Reduktion von \u00dcbergewicht.<\/p>\n<p>Unterschiedliche Medikamente kommen zur Schmerzreduktion und Entz\u00fcndungshemmung in Frage. Hierzu z\u00e4hlen wir Nicht Steroidale Antirheumatika (NSAR) wie Diclofenac, Ibuprofen oder die Cox 2 Hemmer. So genannte SYSADOA (Symptomatic Slow Acting Drugs in Osteoarthritis) sind nicht direkt schmerzlindernd und beeinflussen den Verlauf der Krankheit nicht.<\/p>\n<p>DMOAD (Disease Modifying Osteoarthritis Drugs \u2013 fr\u00fcher als Chondroprotektiva bezeichnet) sollen dagegen eine Verlangsamung der Knorpeldegeneration und\/oder eine Verst\u00e4rkung der Knorpelregeneration bewirken.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1143 alignright\" src=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/Behandlung-300x245.jpg\" alt=\"\" width=\"300\" height=\"245\" srcset=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/Behandlung-300x245.jpg 300w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/Behandlung.jpg 558w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Durchaus hilfreich k\u00f6nnen auch Physiotherapie zum Erhalt der Gelenkfunktion, W\u00e4rmeanwendungen und Eigen\u00fcbungen in B\u00e4dern sein.<\/p>\n<p>Der Nachweis einer wirksamen Therapieform bei Arthrose ist insofern schwierig, da im Verlauf der Krankheit schmerzlose mit schmerzhaften Phasen abwechseln.<\/p>\n<p>Ein wesentlicher Bestandteil der Gelenkfl\u00fcssigkeit im H\u00fcftgelenk ist die Hyalurons\u00e4ure. Diese wird in einem arthrotisch ver\u00e4nderten H\u00fcftgelenk nur unzureichend produziert.<br \/>\nSie hat im Wesentlichen drei Eigenschaften: eine mechanische im Sinne einer besseren \u201eSchmierung\u201c, eine ern\u00e4hrende f\u00fcr den Knorpel und zum dritten wird das \u201eArthrosemilieu\u201c verbessert. Hier kommen also biochemische Effekte zum tragen, die noch nicht ins Detail erforscht sind.<\/p>\n<p>F\u00fcr die Wirksamkeit sprechen auch neuere Forschungsergebnisse, die bei der Arthroseentstehung mehr biochemische als mechanische Faktoren annehmen. So profitieren nicht selten auch Patienten die unter einer Arthrose im fortgeschrittenen Stadium leiden von Hyalurons\u00e4ureinjektionen.<\/p>\n<p>Alternativ k\u00f6nnen auch Injektion mit Eigenblut, so genanntes &#8222;platelet rich plasma PRP oder &#8222;thrombozytenreiches Plasma&#8220; erfolgen. Hier setzt man auf k\u00f6rpereigene Wachstumsfaktoren und entz\u00fcndungshemmende Einfl\u00fcsse um die Arthrosentwicklung zu bremsen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1144 alignright\" src=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/dmoad-300x233.jpeg\" alt=\"\" width=\"300\" height=\"233\" srcset=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/dmoad-300x233.jpeg 300w, https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/dmoad.jpeg 561w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Auch die DMOAD (siehe oben) im Sinne von Nahrungserg\u00e4nzungsmitteln oder so genannte \u201eDi\u00e4tetischen Lebensmittel\u201c haben durchaus ihren Stellenwert. An erster Stelle sind hier die Substanzen Glucosamin und Chondroitin zu nennen, die bei positiver Disposition die Symptome der Arthrose etwas verbessern oder ihr weiteres Fortschreiten verz\u00f6gern k\u00f6nnen.<\/p>\n<p>Leider werden alle diese Pr\u00e4parate seit der Zeit von Ulla Schmidt als Gesundheitsministerin von den gesetzlichen Krankenkassen prinzipiell nicht erstattet. Nichts desto Trotz gibt es viele M\u00f6glichkeiten das Fortschreiten der Arthrose zumindest zu verz\u00f6gern. Diese sollten in einem pers\u00f6nlichen Gespr\u00e4ch beurteilt werden. Ist Ihre Arthrose zu weit fortgeschritten, so dass diese Ma\u00dfnahmen nicht mehr Erfolg versprechend sind, werden wir Ihnen dies auch so mitteilen.<\/p>\n<\/div><\/section>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1123,"parent":1112,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1121","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H\u00fcftgelenkarthrose - MVZ Wiesbaden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00fcftgelenkarthrose - MVZ Wiesbaden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/\" \/>\n<meta property=\"og:site_name\" content=\"MVZ Wiesbaden\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T15:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1172\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/\",\"url\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/\",\"name\":\"H\u00fcftgelenkarthrose - MVZ Wiesbaden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/09\\\/gesunde_huefte.jpg\",\"datePublished\":\"2023-09-11T14:32:36+00:00\",\"dateModified\":\"2023-09-11T15:09:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/09\\\/gesunde_huefte.jpg\",\"contentUrl\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/09\\\/gesunde_huefte.jpg\",\"width\":1172,\"height\":617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/hueftgelenkarthrose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bereiche\",\"item\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"H\u00fcfte\",\"item\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/bereiche\\\/huefte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"H\u00fcftgelenkarthrose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/#website\",\"url\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/\",\"name\":\"MVZ Wiesbaden\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/atos-mvz.de\\\/wiesbaden\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00fcftgelenkarthrose - MVZ Wiesbaden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/","og_locale":"de_DE","og_type":"article","og_title":"H\u00fcftgelenkarthrose - MVZ Wiesbaden","og_url":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/","og_site_name":"MVZ Wiesbaden","article_modified_time":"2023-09-11T15:09:11+00:00","og_image":[{"width":1172,"height":617,"url":"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/","url":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/","name":"H\u00fcftgelenkarthrose - MVZ Wiesbaden","isPartOf":{"@id":"https:\/\/atos-mvz.de\/wiesbaden\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/#primaryimage"},"image":{"@id":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/#primaryimage"},"thumbnailUrl":"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte.jpg","datePublished":"2023-09-11T14:32:36+00:00","dateModified":"2023-09-11T15:09:11+00:00","breadcrumb":{"@id":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/#primaryimage","url":"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte.jpg","contentUrl":"https:\/\/atos-mvz.de\/wiesbaden\/wp-content\/uploads\/sites\/22\/2023\/09\/gesunde_huefte.jpg","width":1172,"height":617},{"@type":"BreadcrumbList","@id":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/hueftgelenkarthrose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/atos-mvz.de\/wiesbaden\/startseite\/"},{"@type":"ListItem","position":2,"name":"Bereiche","item":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/"},{"@type":"ListItem","position":3,"name":"H\u00fcfte","item":"https:\/\/atos-mvz.de\/wiesbaden\/bereiche\/huefte\/"},{"@type":"ListItem","position":4,"name":"H\u00fcftgelenkarthrose"}]},{"@type":"WebSite","@id":"https:\/\/atos-mvz.de\/wiesbaden\/#website","url":"https:\/\/atos-mvz.de\/wiesbaden\/","name":"MVZ Wiesbaden","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atos-mvz.de\/wiesbaden\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/pages\/1121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/comments?post=1121"}],"version-history":[{"count":15,"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/pages\/1121\/revisions"}],"predecessor-version":[{"id":1131,"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/pages\/1121\/revisions\/1131"}],"up":[{"embeddable":true,"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/pages\/1112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/media\/1123"}],"wp:attachment":[{"href":"https:\/\/atos-mvz.de\/wiesbaden\/wp-json\/wp\/v2\/media?parent=1121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}